{"id":2202,"date":"2024-02-16T12:44:42","date_gmt":"2024-02-16T11:44:42","guid":{"rendered":"https:\/\/www.ivanaioriolistica.com\/home\/?p=2202"},"modified":"2024-02-16T13:26:16","modified_gmt":"2024-02-16T12:26:16","slug":"biomagnetismo-cose-e-come-funziona","status":"publish","type":"post","link":"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/","title":{"rendered":"Biomagnetismo: cos\u2019\u00e8 e come funziona?"},"content":{"rendered":"<p>Dedico questo articolo al <strong>Biomagnetismo, <\/strong>spiegando\u00a0cos&#8217;\u00e8, come funziona e perch\u00e9 sceglierlo per il trattamento di diverse condizioni salutari, sottolineando benefici ed efficacia nel fornire una soluzione naturale per migliorare il benessere del nostro organismo.<\/p>\n<p>Con\u00a0 il trattamento andiamo a stimolare, con una tecnica basata sull&#8217;uso di campi magnetici, la capacit\u00e0 di autoguarigione dell&#8217;organismo, mirando a correggere le disarmonie energetiche che, se non trattate, possono sfociare in disturbi e patologie.<\/p>\n<p>Continua a leggere per scoprire di pi\u00f9 su questo nuovo approccio al benessere e a una migliore qualit\u00e0 della vita.<\/p>\n<h2>Cos\u2019\u00e8 il Biomagnetismo<\/h2>\n<p>Cos&#8217;\u00e8 il biomagnetismo? Si tratta di una terapia complementare fondata sull&#8217;uso di magneti per riequilibrare il pH del corpo e, di conseguenza, neutralizzare virus, batteri, funghi e parassiti, considerati la causa principale di diverse malattie.<\/p>\n<p>Il pH \u00e8 il potenziale di idrogeno o grado di acidit\u00e0 o alcalinit\u00e0 che contiene l&#8217;acqua del nostro corpo. La sua modificazione origina uno sbilanciamento nell&#8217;organismo, favorendo lo sviluppo di disturbi e malattie.<\/p>\n<p>L\u2019intervento del Biomagnetismo si concentra sulla radice delle alterazioni: per questo motivo, riveste un&#8217;importanza fondamentale come metodo di prevenzione.<\/p>\n<p>La tecnica curativa \u00e8 nota anche con il termine Coppia Biomagnetica ed \u00e8 stata messa in pratica dal Dr. Isaac Goiz Dur\u00e1n, medico scientifico padre della scoperta, come:<\/p>\n<ul>\n<li>sistema integrativo e non invasivo<\/li>\n<li>strumento complementare sviluppato per aiutare le persone a recuperare la propria salute.<\/li>\n<\/ul>\n<p>L\u2019obiettivo \u00e8 la creazione delle giuste condizioni per accelerare il processo di riabilitazione, applicando campi magnetici statici in diverse aree del corpo che sono in &#8220;<strong>Risonanza Biomagnetica<\/strong>&#8220;. Il termine indica la condizione in cui cellule e tessuti del corpo umano reagiscono in modo specifico ai campi magnetici. Attraverso l&#8217;applicazione dei magneti in queste aree &#8220;resonanti&#8221;, si mira a riequilibrare l&#8217;energia del corpo e a favorire un processo di guarigione naturale.<\/p>\n<p>Per comprenderci: l&#8217;obiettivo \u00e8 utilizzare i campi magnetici per influenzare positivamente il sistema energetico del corpo e facilitare il suo ritorno a uno stato di salute ottimale.<\/p>\n<p>Le aree su cui intervenire vengono individuate attraverso un<strong> test kinesiologico<\/strong> basato su una metodologia descritta dal Dr. Goiz Dur\u00e1n.<\/p>\n<p>Con la Coppia Biomagnetica abbiamo a disposizione una mappa precisa dei punti nel corpo in cui collocare le coppie di magneti, utili a identificare un terreno biologico in grado di sostenere microrganismi patogeni o disfunzioni organiche e trattarlo in modo adeguato.<\/p>\n<p>Il Biomagnetismo agisce alla radice dell&#8217;alterazione, non solo sui sintomi. Per questo motivo, questa tecnica riveste un grande valore anche in termini di prevenzione, poich\u00e9 \u00e8 in grado di individuare i campi magnetici alterati e le variazioni del pH del nostro organismo prima che i segnali di malessere si manifestino.<\/p>\n<h2>Come funziona<\/h2>\n<blockquote>\n<p style=\"text-align: right;\">\u201cCon il Biomagnetismo si trattano le cause e non soltanto i sintomi della malattia\u201d (cit. Dott. Goiz Dur\u00e1n)<\/p>\n<\/blockquote>\n<p>Come funziona una sessione di Biomagnetismo? Scopriamo insieme le tre fasi principali:<\/p>\n<ol>\n<li>tracking con ricerca dei punti attivi sul corpo del ricevente utilizzando diverse tecniche metodologiche<\/li>\n<li>impattazione cio\u00e8 posizionamento dei magneti per favorire equilibrio del pH e armonizzazione energetica dell\u2019organismo<\/li>\n<li>verifica dell&#8217;efficacia del trattamento attraverso ulteriori test e osservazioni per confermare la disattivazione dei punti precedentemente individuati e valutare eventuali miglioramenti.<\/li>\n<\/ol>\n<p>Il nostro corpo \u00e8 un sistema di circuiti elettrici che funziona emettendo e ricevendo costantemente energia generata dalla propria parte fisica, mentale ed emozionale del corpo e dall&#8217;ambiente che ci circonda.<\/p>\n<p>Il <strong>Biomagnetista<\/strong> posiziona i magneti sulle aree del corpo interessate, normalizzano l\u2019elettricit\u00e0, cio\u00e8 segnali elettrici che vengono generati e rilevati dai nostri organi, muscoli, cervello e ghiandole.<\/p>\n<p>Il passo successivo \u00e8 la trasmissione alle periferiche nervose, con conseguente riequilibrio del pH delle cellule. Si ottiene il riconoscimento, da parte del sistema immunologico, dei microrganismi patogeni, apportando un miglioramento all\u2019organismo.<\/p>\n<p>La durata totale di una sessione di trattamento pu\u00f2 variare a seconda delle esigenze del ricevente: dai 60 agli 80 minuti.<\/p>\n<p>Il trattamento richiede un minimo di 3 sessioni, precisando che la prima seduta sar\u00e0 concentrata sull\u2019individuazione dei punti di localizzazione e relativo posizionamento dei magneti.<\/p>\n<h2>Perch\u00e9 sceglierlo<\/h2>\n<p>Affidarsi a un naturopata specializzato significa comprendere e cogliere le potenzialit\u00e0 e i benefici di questa tecnica curativa.<\/p>\n<p>Il nostro corpo \u00e8 un sistema di circuiti elettrici che funziona emettendo e ricevendo costantemente energia generata dalla propria parte fisica, mentale ed emozionale del corpo e dall&#8217;ambiente che ci circonda.<\/p>\n<p>Dal punto di vista pratico, il Biomagnetismo ha un\u2019influenza positiva su corpo e organismo, perch\u00e9 utile a trattare malattie:<\/p>\n<ul>\n<li>infettive<\/li>\n<li>contagiose<\/li>\n<li>cronico-degenerative<\/li>\n<li>metaboliche<\/li>\n<li>disfunzionali<\/li>\n<li>autoimmuni<\/li>\n<li>psico-emozionali<\/li>\n<li>tumorali e da intossicazione.<\/li>\n<\/ul>\n<p>La Coppia Biomagnetica \u00e8 una tecnica integrativa che non interferisce con altre metodologie, non ha effetti negativi, non \u00e8 invasiva. Pu\u00f2 essere usata in modo preventivo, durante i trattamenti medici convenzionali o nella riabilitazione, senza alterare le prescrizioni o gli interventi medici.<\/p>\n<p>Questo approccio si rivela semplice, immediato, efficace perch\u00e9<\/p>\n<ul>\n<li>potenzia una risposta immunitaria efficace<\/li>\n<li>migliora la tonicit\u00e0 vascolare<\/li>\n<li>favorisce il flusso sanguigno e di altri fluidi corporei<\/li>\n<li>contribuisce al corretto funzionamento di organi e sistemi<\/li>\n<li>promuove un&#8217;adeguata attivazione metabolica<\/li>\n<li>supporta il processo di autoriparazione dei tessuti<\/li>\n<li>riduce gli effetti negativi dello stress sul corpo.<\/li>\n<\/ul>\n<p>Il Biomagnetismo presenta alcune <strong>controindicazioni: <\/strong>non \u00e8 indicato per pazienti sottoposti a chemioterapia o radioterapia, donne in gravidanza e persone con pacemaker o altri dispositivi elettromedicali impiantabili.<\/p>\n<p>Concludendo, \u00e8 importante seguire due precauzioni generali:<\/p>\n<ul>\n<li>prima di iniziare qualsiasi trattamento \u00e8 importante consultare il proprio medico<\/li>\n<li>scegliere un professionista esperto, riconosciuto e qualificato cio\u00e8 un Biomagnetista.<\/li>\n<\/ul>\n<p>Incorporare il <strong>Biomagnetismo Medico<\/strong> nella mia pratica naturopatica significa offrire un&#8217;opzione di trattamento radicata nella scienza naturale, che avanzata nella sua capacit\u00e0 di promuovere la salute a livelli multipli. Ogni sessione \u00e8 personalizzata per rispondere alle esigenze uniche del tuo corpo, guidandoti delicatamente verso un stato di benessere duraturo.<\/p>\n<p>La personalizzazione \u00e8 fondamentale nella mia metodologia di lavoro. Ogni <a href=\"https:\/\/www.ivanaioriolistica.com\/home\/consulenza-naturopatica-cose-e-come-si-svolge\/\">consulenza naturopatica<\/a> \u00e8 mirata alle esigenze uniche di ciascun individuo, garantendo un trattamento su misura per massimizzare i benefici e offrire una guida per coloro che mettono al primo posto il benessere e l&#8217;evoluzione propria e altrui.<\/p>\n<p>Ho scritto questo articolo per far conoscere i benefici dei magneti e guidarti attraverso il mondo del Biomagnetismo in un percorso di crescita e liberazione.<\/p>\n<p>Contattami per una consulenza e\u00a0continua a seguire il mio blog per scoprire preziosi consigli naturopatici: ti aspetto qui.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dedico questo articolo al Biomagnetismo, spiegando\u00a0cos&#8217;\u00e8, come funziona e perch\u00e9 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2213,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-2202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trattamenti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Biomagnetismo: cos\u2019\u00e8 e come funziona? - Ivana Iori Olistica del Benessere - Massaggi Olbia<\/title>\n<meta name=\"description\" content=\"Biomagnetismo: cos&#039;\u00e8, come funziona e perch\u00e9 sceglierlo per il trattamento naturopatico di diverse condizioni salutari.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biomagnetismo: cos\u2019\u00e8 e come funziona? - Ivana Iori Olistica del Benessere - Massaggi Olbia\" \/>\n<meta property=\"og:description\" content=\"Biomagnetismo: cos&#039;\u00e8, come funziona e perch\u00e9 sceglierlo per il trattamento naturopatico di diverse condizioni salutari.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/\" \/>\n<meta property=\"og:site_name\" content=\"Ivana Iori Olistica del Benessere - Massaggi Olbia\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-16T11:44:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-16T12:26:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ivanaioriolistica.com\/home\/wp-content\/uploads\/2024\/02\/Biomagnetismo-cose-e-come-funziona.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ivana Iori\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ivana Iori\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/\",\"url\":\"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/\",\"name\":\"Biomagnetismo: cos\u2019\u00e8 e come funziona? - Ivana Iori Olistica del Benessere - Massaggi Olbia\",\"isPartOf\":{\"@id\":\"https:\/\/www.ivanaioriolistica.com\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ivanaioriolistica.com\/home\/wp-content\/uploads\/2024\/02\/Biomagnetismo-cose-e-come-funziona.png\",\"datePublished\":\"2024-02-16T11:44:42+00:00\",\"dateModified\":\"2024-02-16T12:26:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.ivanaioriolistica.com\/home\/#\/schema\/person\/2b6edcd30c0a520c470fe23a17cb4f82\"},\"description\":\"Biomagnetismo: cos'\u00e8, come funziona e perch\u00e9 sceglierlo per il trattamento naturopatico di diverse condizioni salutari.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/#primaryimage\",\"url\":\"https:\/\/www.ivanaioriolistica.com\/home\/wp-content\/uploads\/2024\/02\/Biomagnetismo-cose-e-come-funziona.png\",\"contentUrl\":\"https:\/\/www.ivanaioriolistica.com\/home\/wp-content\/uploads\/2024\/02\/Biomagnetismo-cose-e-come-funziona.png\",\"width\":800,\"height\":542,\"caption\":\"Biomagnetismo: cos\u2019\u00e8 e come funziona?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ivanaioriolistica.com\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biomagnetismo: cos\u2019\u00e8 e come funziona?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ivanaioriolistica.com\/home\/#website\",\"url\":\"https:\/\/www.ivanaioriolistica.com\/home\/\",\"name\":\"Ivana Iori Olistica del Benessere - Massaggi Olbia\",\"description\":\"Riequilibrio Energetico e Benessere Psicofisico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ivanaioriolistica.com\/home\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ivanaioriolistica.com\/home\/#\/schema\/person\/2b6edcd30c0a520c470fe23a17cb4f82\",\"name\":\"Ivana Iori\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ivanaioriolistica.com\/home\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/37900601ba1405938b35f0287ee6f52a2432d72afa6d7be37c35c3e266fa0a0e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/37900601ba1405938b35f0287ee6f52a2432d72afa6d7be37c35c3e266fa0a0e?s=96&d=mm&r=g\",\"caption\":\"Ivana Iori\"},\"url\":\"https:\/\/www.ivanaioriolistica.com\/home\/author\/luisella-scanu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biomagnetismo: cos\u2019\u00e8 e come funziona? - Ivana Iori Olistica del Benessere - Massaggi Olbia","description":"Biomagnetismo: cos'\u00e8, come funziona e perch\u00e9 sceglierlo per il trattamento naturopatico di diverse condizioni salutari.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/","og_locale":"it_IT","og_type":"article","og_title":"Biomagnetismo: cos\u2019\u00e8 e come funziona? - Ivana Iori Olistica del Benessere - Massaggi Olbia","og_description":"Biomagnetismo: cos'\u00e8, come funziona e perch\u00e9 sceglierlo per il trattamento naturopatico di diverse condizioni salutari.","og_url":"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/","og_site_name":"Ivana Iori Olistica del Benessere - Massaggi Olbia","article_published_time":"2024-02-16T11:44:42+00:00","article_modified_time":"2024-02-16T12:26:16+00:00","og_image":[{"width":800,"height":542,"url":"https:\/\/www.ivanaioriolistica.com\/home\/wp-content\/uploads\/2024\/02\/Biomagnetismo-cose-e-come-funziona.png","type":"image\/png"}],"author":"Ivana Iori","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Ivana Iori","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/","url":"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/","name":"Biomagnetismo: cos\u2019\u00e8 e come funziona? - Ivana Iori Olistica del Benessere - Massaggi Olbia","isPartOf":{"@id":"https:\/\/www.ivanaioriolistica.com\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/#primaryimage"},"image":{"@id":"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ivanaioriolistica.com\/home\/wp-content\/uploads\/2024\/02\/Biomagnetismo-cose-e-come-funziona.png","datePublished":"2024-02-16T11:44:42+00:00","dateModified":"2024-02-16T12:26:16+00:00","author":{"@id":"https:\/\/www.ivanaioriolistica.com\/home\/#\/schema\/person\/2b6edcd30c0a520c470fe23a17cb4f82"},"description":"Biomagnetismo: cos'\u00e8, come funziona e perch\u00e9 sceglierlo per il trattamento naturopatico di diverse condizioni salutari.","breadcrumb":{"@id":"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/#primaryimage","url":"https:\/\/www.ivanaioriolistica.com\/home\/wp-content\/uploads\/2024\/02\/Biomagnetismo-cose-e-come-funziona.png","contentUrl":"https:\/\/www.ivanaioriolistica.com\/home\/wp-content\/uploads\/2024\/02\/Biomagnetismo-cose-e-come-funziona.png","width":800,"height":542,"caption":"Biomagnetismo: cos\u2019\u00e8 e come funziona?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ivanaioriolistica.com\/home\/biomagnetismo-cose-e-come-funziona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ivanaioriolistica.com\/home\/"},{"@type":"ListItem","position":2,"name":"Biomagnetismo: cos\u2019\u00e8 e come funziona?"}]},{"@type":"WebSite","@id":"https:\/\/www.ivanaioriolistica.com\/home\/#website","url":"https:\/\/www.ivanaioriolistica.com\/home\/","name":"Ivana Iori Olistica del Benessere - Massaggi Olbia","description":"Riequilibrio Energetico e Benessere Psicofisico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ivanaioriolistica.com\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.ivanaioriolistica.com\/home\/#\/schema\/person\/2b6edcd30c0a520c470fe23a17cb4f82","name":"Ivana Iori","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ivanaioriolistica.com\/home\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/37900601ba1405938b35f0287ee6f52a2432d72afa6d7be37c35c3e266fa0a0e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/37900601ba1405938b35f0287ee6f52a2432d72afa6d7be37c35c3e266fa0a0e?s=96&d=mm&r=g","caption":"Ivana Iori"},"url":"https:\/\/www.ivanaioriolistica.com\/home\/author\/luisella-scanu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ivanaioriolistica.com\/home\/wp-json\/wp\/v2\/posts\/2202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ivanaioriolistica.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ivanaioriolistica.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ivanaioriolistica.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ivanaioriolistica.com\/home\/wp-json\/wp\/v2\/comments?post=2202"}],"version-history":[{"count":11,"href":"https:\/\/www.ivanaioriolistica.com\/home\/wp-json\/wp\/v2\/posts\/2202\/revisions"}],"predecessor-version":[{"id":2214,"href":"https:\/\/www.ivanaioriolistica.com\/home\/wp-json\/wp\/v2\/posts\/2202\/revisions\/2214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ivanaioriolistica.com\/home\/wp-json\/wp\/v2\/media\/2213"}],"wp:attachment":[{"href":"https:\/\/www.ivanaioriolistica.com\/home\/wp-json\/wp\/v2\/media?parent=2202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ivanaioriolistica.com\/home\/wp-json\/wp\/v2\/categories?post=2202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ivanaioriolistica.com\/home\/wp-json\/wp\/v2\/tags?post=2202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}